{"id":19910,"date":"2018-09-11T11:17:30","date_gmt":"2018-09-11T16:17:30","guid":{"rendered":"https:\/\/www.syntorial.com\/\/?p=19910"},"modified":"2025-01-09T10:45:27","modified_gmt":"2025-01-09T10:45:27","slug":"fat-juicy-analog-style-bass-tutorial","status":"publish","type":"post","link":"https:\/\/www.syntorial.com\/de\/tutorials\/fat-juicy-analog-style-bass-tutorial\/","title":{"rendered":"Tutorial: Fetter, saftiger Bass im Analog-Stil"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tutorial: Fetter, saftiger Bass im Analog-Stil\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/aX8CTXZ8o_w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Synth-Tutorial zeigt dir Joe Hanley, der Entwickler von Syntorial, Schritt f\u00fcr Schritt, wie er einen Bass-Patch im Analog-Stil erstellt. Vergiss nicht, den Monark-Patch hier herunterzuladen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Native Instruments' Monark \u2013 <a href=\"http:\/\/www.mediafire.com\/file\/si2snxstrh4tqk6\/Fat_Analog_Bass.nrkt.zip\/file\" target=\"_blank\" rel=\"noopener\">Download<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VIDEO-TRANSKRIPT<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hi, ich bin Joe Hanley, Entwickler von Syntorial, und willkommen zu einem kurzen Synth-Tutorial, in dem ich dir zeige, wie man einen fetten Bass im Analog-Stil erstellt. So klingt er. Es ist ein wirklich einfacher Patch, der nicht viel Programmierarbeit erfordert. Aber es ist eine Sammlung sehr subtiler Anpassungen \u2013 und einige davon kommen den meisten Leuten gar nicht in den Sinn. Es ist so ein gefragter Sound: Wie bekommt man diesen fetten, warmen Analog-Bass hin, vor allem aus einem Software-Synth?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist kein gew\u00f6hnliches Synth-Tutorial. Das ist Syntorial. Synth-Programmierung leicht gemacht. Mit einem spielerischen Training lernst du, Synth-Patches nach Geh\u00f6r zu programmieren. Jede Lektion beginnt mit einer Demonstration, gefolgt von einer interaktiven Challenge \u2013 \u00fcber 200 Lektionen insgesamt. Nach Abschluss des Programms kannst du die Sounds, die du h\u00f6rst, mit fast jedem Synthesizer nachbauen. Probiere das preisgekr\u00f6nte Syntorial noch heute aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das hier ist ein Software-Synth, der nach einem Analog-Synth modelliert ist \u2013 dem Moog. Er hei\u00dft Monark von Native Instruments, aber es gibt jede Menge Synths dieser Art. Um diesen Sound hinzubekommen, brauchst du wirklich nur einen Synth mit einem Filter im Analog-Stil und einer Filter-Drive-Option \u2013 dazu gleich mehr. Okay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Erstes initialisiere ich das Ganze, damit wir einen einfachen \u2026 Sound haben. Und ich erh\u00f6he unseren Range um eine Oktave. Ich h\u00e4tte auch einfach h\u00f6her auf dem Keyboard spielen k\u00f6nnen, aber ich musste das so machen, weil wir sp\u00e4ter zum Key-Tracking kommen und das von dieser Einstellung abh\u00e4ngt. Im Moment haben wir eine Rechteckwelle. Aber ich m\u00f6chte eine S\u00e4gezahnwelle nehmen. Eine Rechteckwelle w\u00fcrde auch funktionieren, aber wenn alle Einstellungen fertig sind, wirst du sehen, wie dieser S\u00e4gezahn uns diesen richtig warmen, klassischen Synth-Sound liefert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um unseren Bass-Sound zu bekommen, m\u00fcssen wir ein paar H\u00f6hen wegnehmen, damit der Sound mehr auf den Tieftonbereich fokussiert ist, also \u2026 Lass uns den Cutoff runterdrehen. Und jetzt haben wir einen einfachen, runden Bass. Das ist okay. Das ist gut f\u00fcr einen dezenten Tieftonbereich. Perfekt zum Layern mit anderen Bass-Sounds. Angenommen, du hast einen Bass-Sound erstellt, der viel mehr Charakter hat. Er ist brillanter, aber es fehlt ihm der Tieftonbereich. Manchmal reicht es, einen einfachen Synth im Analog-Stil mit S\u00e4gezahn und heruntergedrehtem Cutoff dazuzulayern, um diesen sch\u00f6nen Tieftonbereich zu bekommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber wir wollen, dass dieser Sound selbst etwas pr\u00e4senter und viel fetter wird \u2013 und da kommt unser Filter-Drive ins Spiel. Bei diesem Synth hei\u00dft es Load, aber die Idee ist dieselbe. Wir erh\u00f6hen den Pegel des Signals, das in unseren Filter geht. H\u00f6r mal. Du h\u00f6rst diesen Overdrive. Ein bisschen warme Verzerrung, die aus dem Filter kommt. Filter im Analog-Stil lieben es, \u00fcbersteuert zu werden. Oh, so ein sch\u00f6ner Sound.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist wirklich der Schl\u00fcssel, um aus einem Analog-Filter diesen Analog-Charakter herauszuholen. Es dreht sich alles um diesen Filter-Drive. Und das siehst du auch bei anderen Synths \u2013 zum Beispiel Sylenth1. Der hat einen richtig guten Filter im Analog-Stil, und sein Filter-Drive liefert dir dieselbe Verzerrung, denselben Overdrive. Das ist wirklich der Schl\u00fcssel zu diesem Analog-Sound.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber es gibt noch andere subtile Dinge, die wir tun k\u00f6nnen, um einen fetteren Sound zu bekommen. Eins davon ist, unser AMP-Release nur ein kleines bisschen zu erh\u00f6hen. Bei diesem Synth haben wir Attack, Decay, Sustain, aber keine Release-Option \u2013 was, ja, ein bisschen seltsam ist, oder? Nun, es gibt eine Release-Option, sie ist nur versteckt. Und wenn ich diese Schalter aktiviere, steuert unser Decay-Drehregler sie. Was auch immer unser Decay-Drehregler eingestellt hat, legt auch die Release-Zeit fest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Moment, wenn ich eine Taste loslasse \u2026 schneidet es sehr abrupt ab. Wenn ich es nur ein kleines bisschen erh\u00f6he, verschwindet dieses unangenehme Abschneiden. Wenn ich es stark erh\u00f6he, h\u00f6rst du, wie die Note mit der Zeit ausklingt. Bei null ist es irgendwie unnat\u00fcrlich, aber es l\u00e4sst den Sound auch etwas kleiner wirken. Mit diesem winzigen Ausklang erzeugt es einfach etwas mehr Klang und macht die Noten tats\u00e4chlich fetter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist eine dieser wirklich subtilen Sachen, auf die man nie kommen w\u00fcrde, wenn man einen fetten Sound anstrebt. Es imitiert auch einen echten E-Bass ein bisschen besser. Wei\u00dft du, wenn du eine Note stoppst, sind das nicht null Millisekunden \u2013 das ist die echte Welt, oder? Die Saite h\u00f6rt schnell auf zu schwingen, aber da ist ein winziger Ausklang. So bekommen wir hier einfach etwas mehr von diesem menschlichen, echten Sound.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als N\u00e4chstes: Um dem Ganzen noch mehr von diesem echten Sound zu geben und etwas subtilen Charakter hinzuzuf\u00fcgen, wollen wir, dass die Note etwas brillanter startet und dann dunkler wird. Wir wollen einen subtilen Attack-Transient hinzuf\u00fcgen. Das k\u00f6nnen wir mit unserer Filter-H\u00fcllkurve machen. Also drehe ich zuerst unser Decay hoch. Es passiert noch nichts. Aber wenn ich die Contour erh\u00f6he \u2013 ich mache es stark, damit du wirklich h\u00f6ren kannst, was passiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was passiert, ist: Unsere Contour legt einen h\u00f6heren Cutoff-Punkt fest, bei dem unser Sound startet. Und unser Decay bringt ihn von diesem helleren Punkt runter zu unserem Cutoff. Wenn ich unser Decay erh\u00f6he, dauert es l\u00e4nger. Aber wir wollen es ziemlich schnell, damit es nur am Anfang unseres Sounds ist. Lass uns ungef\u00e4hr hier einstellen. Und wir wollen nicht, dass es so brilliant wird. Es ist nur dieser winzige Transient am Anfang. Jetzt ist es einfach etwas spielbarer. Es ist nicht so statisch, nicht so steif. Es f\u00fchlt sich einfach besser an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denk dran, was ich vorhin gesagt habe: Es hat eigentlich als Rechteck angefangen. Nun, lass uns die Rechteckwelle ausprobieren, mal h\u00f6ren, wie es klingt. Klingt ziemlich gut. Ein bisschen schwerer im Gef\u00fchl, aber \u2026 Es gibt etwas daran, wie der S\u00e4gezahn mit dem Cutoff interagiert. Es gibt uns einfach einen sch\u00f6neren Tieftonbereich. Deshalb habe ich den S\u00e4gezahn genommen. Okay, hier haben wir jetzt einen sch\u00f6nen, fetten Analog-Bass. Er hat etwas mehr Spielbarkeit durch unseren Filter und unser AMP. Klingt gut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber sagen wir, wir wollen noch einen Schritt weitergehen und ein paar kleine Bass-Fills damit machen. Wir wollen etwas pr\u00e4senter sein, aber den Tieftonbereich nicht verlieren. Key-Tracking. Wenn wir beide Schalter aktivieren, macht Key-Tracking h\u00f6here Noten deutlich brillanter als tiefere Noten. Hier ist meine tiefere Note ohne Key-Tracking. Sie ist ein bisschen brillanter. Aber diese Ver\u00e4nderung ist ziemlich subtil. Jetzt vergleichen wir die h\u00f6here Note. Viel brillanter. Ich habe also immer noch diese tiefen Noten. Wenn ich da hochspringe, sticht die Note richtig heraus. Und da ich jetzt ein bisschen zus\u00e4tzliche Helligkeit auf der tiefen Note habe, drehe ich den Cutoff etwas zur\u00fcck. Jetzt bekomme ich beides: meinen Tieftonbereich f\u00fcr diesen fetten Bass und dann diese sch\u00f6nen \u2026 fetten Fills oben drauf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und dann erh\u00f6he ich die Resonance ein bisschen. Und das bewirkt quasi zwei Dinge. Es macht die tiefe Note etwas wuchtiger, etwas basslastiger, und es macht die h\u00f6heren Noten etwas geformter und spitzer. Also, h\u00f6ren wir uns zuerst den Tieftonbereich an. Ich drehe es voll auf, damit du es wirklich h\u00f6ren kannst. Es ist subtil, aber es f\u00fcgt fast so ein Wummern darunter hinzu. Das ist sch\u00f6n. Und was ist mit der hohen Note? H\u00f6rst du das? Es formt sie einfach ein bisschen. Macht sie etwas spitzer. Wir wollen nur etwas Subtiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Warum passiert das? Nun, unsere Resonance hebt unseren Sound am Cutoff-Punkt an. Wenn dein Cutoff heruntergedreht ist, bekommst du eine Anhebung im Tieftonbereich. Wenn dein Cutoff in der Mitte ist, bekommst du eine Anhebung in den Mitten und so weiter. Aber wir haben Key-Tracking aktiviert, richtig? Obwohl unser Drehregler also hier eingestellt ist, ist unser Cutoff tats\u00e4chlich umso h\u00f6her, je h\u00f6her wir spielen. Wenn ich diese tiefe Note spiele, bekomme ich eine Anhebung im Tieftonbereich. Wenn ich die h\u00f6here Note spiele, bekomme ich etwas mehr Anhebung in den Mitten \u2013 es gibt ihr also Form statt Tieftonbereich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wieder eine einfache \u00c4nderung, aber wirklich subtil. Es sind diese Dinge, die okay Patches von gro\u00dfartigen Patches unterscheiden \u2013 diese winzigen letzten Feinschliffe. Und zum Schluss wollen wir den oberen h\u00f6heren Noten etwas Swagger verpassen. Lass uns unser Glide erh\u00f6hen, damit die Noten ineinander \u00fcbergleiten. Das ist ein bisschen zu viel. Vergleich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie gleiten einfach ineinander \u00fcber, sie bekommen ein bisschen Attit\u00fcde. Das Problem ist, wenn ich wieder runtergehen will, dauert es eine Weile. Also aktiviere ich Legato. Wenn ich Noten getrennt spiele, mit Abstand dazwischen: kein Glide. Aber wenn ich sie verbinde: Sie gleiten. Jetzt kann ich mit meinem Spiel entscheiden, wann das Glide einsetzt und wann nicht. Ich kann \u2026 die oberen Noten verbinden, um dieses Glide zu bekommen, und die unteren Noten trennen, damit ich zur\u00fcck zu diesem schweren Bass springen kann. So, da haben wir ihn: einen sch\u00f6nen, fetten, spielbaren Analog-Bass.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist kein gew\u00f6hnliches Synth-Tutorial. Das ist Syntorial. Synth-Programmierung leicht gemacht. Mit einem spielerischen Training lernst du, Synth-Patches nach Geh\u00f6r zu programmieren. Jede Lektion beginnt mit einer Demonstration, gefolgt von einer interaktiven Challenge \u2013 \u00fcber 200 Lektionen insgesamt. Nach Abschluss des Programms kannst du die Sounds, die du h\u00f6rst, mit fast jedem Synthesizer nachbauen. Probiere das preisgekr\u00f6nte Syntorial noch heute aus.<\/p>","protected":false},"excerpt":{"rendered":"<p>In this synth tutorial, Joe Hanley, the creator of Syntorial, will take you step-by-step as he creates an analog-style bass patch. Don\u2019t forget to download the Monark patch below: Native Instruments&#8217; Monark &#8211; Download VIDEO TRANSCRIPT Hi, I&#8217;m Joe Hanley, creator of Syntorial, and welcome to a quick synth tutorial &#8230; <a title=\"Tutorial: Fetter, saftiger Bass im Analog-Stil\" class=\"read-more\" href=\"https:\/\/www.syntorial.com\/de\/tutorials\/fat-juicy-analog-style-bass-tutorial\/\" aria-label=\"Mehr Informationen \u00fcber Fat Juicy Analog-style Bass Tutorial\">Weiterlesen &#8230;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[92],"tags":[60,11],"class_list":["post-19910","post","type-post","status-publish","format-video","hentry","category-tutorials","tag-bass","tag-tutorial","post_format-post-format-video","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/posts\/19910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/comments?post=19910"}],"version-history":[{"count":2,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/posts\/19910\/revisions"}],"predecessor-version":[{"id":56018,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/posts\/19910\/revisions\/56018"}],"wp:attachment":[{"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/media?parent=19910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/categories?post=19910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.syntorial.com\/de\/wp-json\/wp\/v2\/tags?post=19910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}